{"id":46519,"date":"2026-07-09T23:15:29","date_gmt":"2026-07-10T02:15:29","guid":{"rendered":"https:\/\/swimchannel.net\/la\/?p=46519"},"modified":"2026-07-09T23:53:57","modified_gmt":"2026-07-10T02:53:57","slug":"los-podios-del-segundo-dia-de-competencia-en-ibague","status":"publish","type":"post","link":"https:\/\/swimchannel.net\/la\/los-podios-del-segundo-dia-de-competencia-en-ibague\/","title":{"rendered":"Los podios del segundo d\u00eda de competencia en Ibagu\u00e9"},"content":{"rendered":"<p>As\u00ed quedaron los podios del segundo d\u00eda de competencia del Panam Aquatics Swimming Championships en Ibagu\u00e9, Colombia:<\/p>\n<p><strong>100m Mariposa &#8211; Mujeres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00ba Mar\u00eda Gabriela Becerra (COL) 01:03.21<br \/>\n2\u00ba Alma Federica Olguin (ARG) 01:04.62<br \/>\n3\u00ba Isadora Loyola (CHI) 01:04.70<\/p>\n<p><strong>100m Mariposa &#8211; Hombres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00ba Christon Joseph (BAH) 57.72<br \/>\n2\u00ba Franco Maillot (ARG) 59.09<br \/>\n3\u00ba Janiel Espinosa Murillo (COL) 59.62<\/p>\n<p><strong>50m Espalda &#8211; Mujeres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00ba Daniela Airi Tamashiro (PER) 31.12<br \/>\n2\u00ba In\u00e9s Pereyra (ARG) 31.24<br \/>\n3\u00ba Amanda Levin (ARG) 31.29<\/p>\n<p><strong>50m Espalda &#8211; Hombres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00ba Federico Bottos (ARG) 26.89<br \/>\n2\u00ba Carlo Marcelo D\u00edaz (MEX) 28.12<br \/>\n3\u00ba Jamie Tranter (ANT) 28.59<\/p>\n<p><strong>400m Medley &#8211; Mujeres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00b0 Valentina Gonz\u00e1lez (MEX) 05:12.19<br \/>\n2\u00b0 Isidora Loyola (CHI) 05:19.24<br \/>\n3\u00b0 Ana Luc\u00eda Gerbaudo (ARG) 05:21.17<\/p>\n<p><strong>400m Medley &#8211; Hombres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00b0 Oscar Escalada (MEX) 04:52.84<br \/>\n2\u00b0 Franco Maillot (ARG) 04:53.62<br \/>\n3\u00b0 Samir Naranjo (ECU) 04:54.61<\/p>\n<p><strong>200m Libre &#8211; Mujeres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00ba Elissa Sophia Berganza (GUA) 02:09.05<br \/>\n2\u00ba Paloma Palacios Rosas (MEX) 02:09.19<br \/>\n3\u00ba Ana Luc\u00eda Gerbaudo (ARG) 02:11.30<\/p>\n<p><strong>200m Libre &#8211; Hombres (13-15 a\u00f1os)<\/strong><br \/>\n1\u00b0 Diego Castilo (PAN) 01:57.06<br \/>\n2\u00b0 Diego Arturo L\u00f3pez (MEX) 01:57.74<br \/>\n3\u00b0 Andr\u00e9s Rojas (CRC) 01:58.63<\/p>\n<p><strong>4x100m Medley &#8211; Mixto (13-15 a\u00f1os)<\/strong><br \/>\n1\u00b0 M\u00c9XICO 04:15.31<br \/>\n2\u00b0 ARGENTINA 04:15.66<br \/>\n3\u00b0 COLOMBIA 04:20.92<\/p>\n<p><strong>100m Mariposa &#8211; Mujeres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00ba Emma Sabando (ECU) 01:00.88<br \/>\n2\u00ba Yasm\u00edn Silva (PER) 01:02.19<br \/>\n3\u00ba Emilia Sandoval (GUA) 01:03.63<\/p>\n<p><strong>100m Mariposa &#8211; Hombres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00ba Christian Jerome (HAI) 54.09<br \/>\n2\u00ba Santiago Unda (MEX) 55.77<br \/>\n3\u00ba Ian Maldonado (COL) 56.26<\/p>\n<p><strong>50m Espalda &#8211; Mujeres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00ba Skyelar Richards (JAM) 30.12<br \/>\n2\u00ba Alejandra Mart\u00ednez Vergara (MEX) 30.21<br \/>\n3\u00ba Blanca Patricia Vazquez Ramirez (MEX) 30.49<\/p>\n<p><strong>50m Espalda &#8211; Hombres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00ba Omar Ruelas Cisneros (MEX) 26.92<br \/>\n2\u00ba Thiago Marinozzi (ARG) 27.40<br \/>\n3\u00ba Lincoln Tomlinson III (JAM) 27.53<\/p>\n<p><strong>400m Medley &#8211; Mujeres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00b0 Mariana Cabezas (COL) 04:58.80<br \/>\n2\u00b0 Valentina Gonz\u00e1lez (MEX) 05:09.41<br \/>\n3\u00b0 Isabel De La Calle (MEX) 05:12.86<\/p>\n<p><strong>400m Medley &#8211; Hombres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00b0 Mat\u00edas Ram\u00edrez (COL) 04:41.90<br \/>\n2\u00b0 Iker Oliver (MEX) 04:42.05<br \/>\n3\u00b0 Vincenzo Obreros (PER) 04:49.17<\/p>\n<p><strong>200m Libre &#8211; Mujeres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00b0 Karen Rafaela Coello (ECU) 02:04.23<br \/>\n2\u00b0 Mariana Cabezas (COL) 02:06.30<br \/>\n3\u00b0 Carolina Rojas (COL) 02:06.42<\/p>\n<p><strong>200m Libre &#8211; Hombres (16-18 a\u00f1os)<\/strong><br \/>\n1\u00b0 Domenico Sotomayor (PER) 01:52.29<br \/>\n2\u00b0 Nicol\u00e1s Kokidko (COL) 01:53.00<br \/>\n3\u00b0 Christian Jerome (HAI) 01:56.02<\/p>\n<p><strong>4x100m Medley &#8211; Mixto (16-18 a\u00f1os)<\/strong><br \/>\n1\u00b0 M\u00c9XICO 04:05.48<br \/>\n2\u00b0 COLOMBIA 04:06.60<br \/>\n3\u00b0 ECUADOR 04:07.43<\/p>\n<p><strong>100m Mariposa &#8211; Mujeres (19&amp;OVER)<\/strong><br \/>\n1\u00ba Ariel Madison Beltr\u00e1n (MEX) 01:01.52<br \/>\n2\u00ba Roc\u00edo Castro (ARG) 01:03.22<br \/>\n3\u00ba Natalia Su\u00e1rez (ARG) 01:04.26<\/p>\n<p><strong>100m Mariposa &#8211; Hombres (19&amp;OVER)<\/strong><br \/>\n1\u00ba David Arias (COL) 53.55<br \/>\n2\u00ba Emiliano Calle (COL) 54.64<br \/>\n3\u00ba Juan Alvaro Rodr\u00edguez (MEX) 55.21<\/p>\n<p><strong>50m Espalda &#8211; Mujeres (19&amp;OVER)<\/strong><br \/>\n1\u00ba Jasmin Pistelli (COL) 29.09<br \/>\n2\u00ba Sof\u00eda Melo (COL) 29.38<br \/>\n3\u00ba Roc\u00edo Castro (ARG) 29.52<\/p>\n<p><strong>50m Espalda &#8211; Hombres (19&amp;OVER)<\/strong><br \/>\n1\u00ba Guibani Pi\u00f1a Acosta (MEX) 26.22<br \/>\n2\u00ba Edhy Vargas (CHI) 26.61<br \/>\n3\u00ba Erick Blandon (NCA) 26.71<\/p>\n<p><strong>400m Medley &#8211; Mujeres (19&amp;OVER)<\/strong><br \/>\n1\u00b0 Sof\u00eda Melo (COL) 04:55.13<br \/>\n2\u00b0 Alondra Ort\u00edz (CRC) 05:03.50<br \/>\n3\u00b0 Daniela Cordova (ECU) 05:18.21<\/p>\n<p><strong>400m Medley &#8211; Hombres (19&amp;OVER)<\/strong><br \/>\n1\u00b0 Sebasti\u00e1n Camacho (COL) 04:33.59<br \/>\n2\u00b0 Pedro Aguilera (CHI) 04:35.26<br \/>\n3\u00b0 Jos\u00e9 Manuel Real (MEX) 04:36.22<\/p>\n<p><strong>200m Libre &#8211; Mujeres (19&amp;OVER)<\/strong><br \/>\n1\u00b0 Micaela Bernales (PER) 02:06.36<br \/>\n2\u00b0 Andrea P\u00e9rez Armenta (MEX) 02:06.45<br \/>\n3\u00b0 Crystal Lara Ovalle (MEX) 02:07.15<\/p>\n<p><strong>200m Libre &#8211; Hombres (19&amp;OVER)<\/strong><br \/>\n1\u00b0 Juan Manuel Morales (COL) 01:50.19<br \/>\n2\u00b0 Alberto Vega (CRC) 01:56.26<br \/>\n3\u00b0 Mart\u00edn Baldeon (ECU) 01:56.40<\/p>\n<p><strong>4x100m Medley &#8211; Mixto (19&amp;OVER)<\/strong><br \/>\n1\u00b0 COLOMBIA 03:56.46<br \/>\n2\u00b0 M\u00c9XICO 04:05.29<br \/>\n3\u00b0 ARGENTINA 04:02.57<\/p>\n<p>Pueden consultar la p\u00e1gina de resultados en el siguiente link:<a href=\"https:\/\/ibague2026.panamaquaticsevents.com\/home\/\">IBAGU\u00c9 2026<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed quedaron los podios del segundo d\u00eda de competencia del Panam Aquatics Swimming Championships en Ibagu\u00e9, Colombia: 100m Mariposa &#8211; Mujeres (13-15 a\u00f1os) 1\u00ba Mar\u00eda Gabriela Becerra (COL) 01:03.21 2\u00ba Alma Federica Olguin (ARG) 01:04.62 3\u00ba Isadora Loyola (CHI) 01:04.70 100m Mariposa &#8211; Hombres (13-15 a\u00f1os) 1\u00ba Christon Joseph (BAH) 57.72 2\u00ba Franco Maillot (ARG) [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":46522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4265,1],"tags":[],"class_list":["post-46519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natacion","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/posts\/46519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/comments?post=46519"}],"version-history":[{"count":6,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/posts\/46519\/revisions"}],"predecessor-version":[{"id":46528,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/posts\/46519\/revisions\/46528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/media\/46522"}],"wp:attachment":[{"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/media?parent=46519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/categories?post=46519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swimchannel.net\/la\/wp-json\/wp\/v2\/tags?post=46519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}